{"id":4761,"date":"2024-01-21T14:48:54","date_gmt":"2024-01-21T14:48:54","guid":{"rendered":"https:\/\/ipa-aip.org\/sin-categorizar\/a-hundred-years-since-we-lost-comrade-lenin\/"},"modified":"2026-03-12T18:15:08","modified_gmt":"2026-03-12T18:15:08","slug":"cien-anos-desde-que-perdimos-al-camarada-lenin","status":"publish","type":"post","link":"https:\/\/ipa-aip.org\/es\/2024\/01\/21\/cien-anos-desde-que-perdimos-al-camarada-lenin\/","title":{"rendered":"Cien a\u00f1os desde que perdimos al camarada Lenin"},"content":{"rendered":"<div class=\"gb-container gb-container-da3e9517\" id=\"post-hero-centered\"><div class=\"gb-inside-container\">\n<div class=\"gb-container gb-container-e0cc821d post-header-centered\"><div class=\"gb-inside-container\">\n\n<h1 class=\"gb-headline gb-headline-afe86c1f gb-headline-text\">Cien a\u00f1os desde que perdimos al camarada Lenin<\/h1>\n\n\nenero 21, 2024\n\n<\/div><\/div>\n\n<div class=\"gb-container gb-container-983af3cd\" id=\"text-right\"><div class=\"gb-inside-container\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-fa0d0a49\">\n<div class=\"gb-grid-column gb-grid-column-dcc8c539\"><div class=\"gb-container gb-container-dcc8c539\"><div class=\"gb-inside-container\"><\/div><\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-55810cad\"><div class=\"gb-container gb-container-55810cad\"><div class=\"gb-inside-container\">\n\n<p><strong><em>Vijay Prashad, director ejecutivo del <a href=\"https:\/\/thetricontinental.org\/es\/\">Instituto Tricontinental de Investigaci\u00f3n Social<\/a>, corresponsal jefe de Globetrotter y editor jefe de <a href=\"https:\/\/mayday.leftword.com\/\">LeftWord Books<\/a> (Nueva Delhi).<\/em><\/strong><\/p>\n\n\n\n<p>Vladimir Ilich Ulanov (1870-1924) era conocido por su seud\u00f3nimo: Lenin. Fue, al igual que sus hermanos, un revolucionario, lo que en el contexto de la Rusia zarista signific\u00f3 que pasara largos a\u00f1os en prisi\u00f3n y en el exilio. Lenin ayud\u00f3 a construir el Partido Laborista Socialdem\u00f3crata Ruso tanto con su labor intelectual como organizativa. Los escritos de Lenin no son solo sus propias palabras, sino el resumen de la actividad y el pensamiento de los miles de activistas cuyo camino se cruz\u00f3 con el suyo. Fue la notable habilidad de Lenin para desarrollar las experiencias de los activistas en el terreno te\u00f3rico lo que dio forma a lo que llamamos leninismo. No es de extra\u00f1ar que el marxista h\u00fangaro Gy\u00f6rgy Luk\u00e1cs llamara a Lenin \u00abel \u00fanico te\u00f3rico igual a Marx que ha producido la lucha por la liberaci\u00f3n del proletariado\u00bb.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>CONSTRUIR UNA REVOLUCI\u00d3N<\/strong><\/h6>\n\n\n\n<p>En 1896, cuando estallaron las huelgas espont\u00e1neas en las f\u00e1bricas de San Petersburgo, los revolucionarios socialistas se vieron sorprendidos y desorientados. Cinco a\u00f1os m\u00e1s tarde, Lenin escribi\u00f3: \u00ablos revolucionarios se quedaron rezagados con respecto a este estallido, tanto en sus &#8216;teor\u00edas&#8217; como en su actividad; no lograron establecer una organizaci\u00f3n constante y continua capaz de dirigir todo el movimiento\u00bb. Lenin consideraba necesario corregir este retraso.<\/p>\n\n\n\n<p>La mayor\u00eda de los principales escritos de Lenin siguieron esta idea. Lenin desarroll\u00f3 las contradicciones del capitalismo en Rusia (Desarrollo del capitalismo en Rusia, 1896), lo que le permiti\u00f3 comprender c\u00f3mo el campesinado del extenso Imperio zarista ten\u00eda un car\u00e1cter proletario. Sobre esta base, Lenin defendi\u00f3 la alianza obrero-campesina contra el zarismo y los capitalistas. Lenin, a partir de su compromiso con la lucha de masas y su lectura te\u00f3rica, comprendi\u00f3 que los socialdem\u00f3cratas, al igual que el sector m\u00e1s liberal de la burgues\u00eda y los arist\u00f3cratas, no eran capaces de impulsar una revoluci\u00f3n burguesa, y mucho menos el movimiento que llevar\u00eda a la emancipaci\u00f3n del campesinado y los obreros. Este an\u00e1lisis se plasm\u00f3 en Dos t\u00e1cticas de la socialdemocracia en la revoluci\u00f3n democr\u00e1tica (1905). Dos t\u00e1cticas es quiz\u00e1 el primer gran tratado marxista que demuestra la necesidad de una revoluci\u00f3n socialista, incluso en un pa\u00eds \u00abatrasado\u00bb, donde los obreros y los campesinos tendr\u00edan que aliarse para romper las instituciones de servidumbre.<\/p>\n\n\n\n<p>Estos dos textos muestran a Lenin evitando la opini\u00f3n de que la Revoluci\u00f3n Rusa pod\u00eda saltarse el desarrollo capitalista (como suger\u00edan los populistas -narodniki-) o que ten\u00eda que pasar por el capitalismo (como argumentaban los dem\u00f3cratas liberales). Ninguna de las dos v\u00edas era posible ni necesaria. El capitalismo ya hab\u00eda entrado en Rusia, un hecho que los populistas no reconoc\u00edan, y pod\u00eda ser superado por una revoluci\u00f3n obrera y campesina, un hecho que los dem\u00f3cratas liberales discut\u00edan. La Revoluci\u00f3n de 1917 y el experimento sovi\u00e9tico demostraron el punto de vista de Lenin.<\/p>\n\n\n\n<p>Una vez establecido que las \u00e9lites liberales de la Rusia zarista no ser\u00edan capaces de dirigir una revoluci\u00f3n obrera y campesina, ni siquiera una revoluci\u00f3n burguesa, Lenin dirigi\u00f3 su atenci\u00f3n a la situaci\u00f3n internacional. Sentado en el exilio en Suiza, Lenin vio c\u00f3mo los socialdem\u00f3cratas capitulaban ante el belicismo en 1914 y entregaban a la clase obrera a la guerra mundial. Frustrado por la traici\u00f3n de los socialdem\u00f3cratas, Lenin escribi\u00f3 un importante texto -El imperialismo- que desarrollaba una comprensi\u00f3n l\u00facida del crecimiento del capital financiero y de las empresas monopolistas, as\u00ed como del conflicto intercapitalista e interimperialista. Fue en este texto donde Lenin explor\u00f3 las limitaciones de los movimientos socialistas en Occidente, con la aristocracia obrera como barrera a la lucha socialista, y el potencial para la revoluci\u00f3n en Oriente, donde podr\u00eda encontrarse el \u00abeslab\u00f3n m\u00e1s d\u00e9bil\u00bb de la cadena imperialista. Los cuadernos de Lenin muestran que ley\u00f3 148 libros y 213 art\u00edculos en ingl\u00e9s, franc\u00e9s, alem\u00e1n y ruso para aclarar su pensamiento sobre el imperialismo contempor\u00e1neo. Una evaluaci\u00f3n l\u00facida del imperialismo de este tipo garantiz\u00f3 que Lenin desarrollara una posici\u00f3n firme sobre los derechos de las naciones a la autodeterminaci\u00f3n, tanto si estas naciones estaban dentro del Imperio zarista como de cualquier otro imperio europeo. El n\u00facleo del anticolonialismo de la URSS -desarrollado en la Internacional Comunista (Comintern)- se encuentra aqu\u00ed.<\/p>\n\n\n\n<p>El t\u00e9rmino \u00abimperialismo\u00bb, tan central en la expansi\u00f3n de la tradici\u00f3n marxista de Lenin, se refiere al desarrollo desigual del capitalismo a escala mundial y al uso de la fuerza para mantener esa desigualdad. Ciertas partes del planeta, principalmente aquellas que tuvieron una historia previa de colonizaci\u00f3n, permanecen en una posici\u00f3n de subordinaci\u00f3n, con su capacidad para elaborar una agenda de desarrollo nacional independiente limitada por los tent\u00e1culos del poder pol\u00edtico, econ\u00f3mico, social y cultural extranjero. En nuestro tiempo, han surgido nuevas teor\u00edas que sugieren que las nuevas condiciones ya no pueden ser entendidas por la teor\u00eda leninista del imperialismo. Algunas personas de izquierda rechazan la idea de la estructura neocolonial de la econom\u00eda mundial, en la que el bloque imperialista, dirigido por Estados Unidos, utiliza todas sus fuentes de poder para mantener esta estructura. Otros, incluso en la izquierda, sostienen que el mundo es ahora plano y que ya no hay un Norte Global que oprima a un Sur Global, y que las \u00e9lites de ambas zonas forman parte de una burgues\u00eda internacional.<\/p>\n\n\n\n<p>Ninguna de estas objeciones se sostiene cuando se confronta tanto con los crecientes niveles de violencia perpetuados por el bloque imperialista como con los crecientes niveles de desigualdad relativa entre el Norte y el Sur, a pesar del crecimiento de las \u00e9lites capitalistas en el Sur. Algunos elementos del Imperialismo de Lenin son, por supuesto, anticuados, ya que fue escrito hace cien a\u00f1os, y requerir\u00edan una cuidadosa reelaboraci\u00f3n. Pero la esencia de la teor\u00eda es v\u00e1lida: la insistencia en la tendencia de las empresas capitalistas a convertirse en monopolios, la crueldad con la que el capital financiero drena la riqueza del Sur Global y el uso de la fuerza para contener las ambiciones de los pa\u00edses del Sur de trazar su propia agenda de desarrollo.<\/p>\n\n\n\n<p>Una de las intervenciones m\u00e1s vitales de Lenin, que atrajo a los habitantes de las colonias, fue la idea de que el imperialismo nunca desarrollar\u00eda la colonia y que solo las fuerzas socialistas, en colaboraci\u00f3n con las secciones de liberaci\u00f3n nacional, ser\u00edan capaces tanto de luchar por la independencia nacional como de avanzar luego hacia el socialismo. La feroz determinaci\u00f3n anticolonialista de Lenin atrajo a sus ideas a los habitantes del mundo colonizado, raz\u00f3n por la que se unieron con tanto entusiasmo a la Comintern despu\u00e9s de 1919. Ho Chi Minh ley\u00f3 las tesis de la Comintern sobre cuestiones nacionales y coloniales y llor\u00f3. Le pareci\u00f3 una \u00abgu\u00eda milagrosa\u00bb para la lucha del pueblo de Indochina. \u00abDe la experiencia de la Revoluci\u00f3n Rusa\u00bb, escribi\u00f3 Ho Chi Minh, \u00abdebemos tener al pueblo -tanto a la clase obrera como a los campesinos- en el centro de nuestra lucha. Necesitamos un partido fuerte, una voluntad fuerte, con sacrificio y unanimidad en nuestro centro\u00bb. \u00abComo un sol brillante\u00bb, a\u00f1adi\u00f3 Ho Chi Minh, \u00abla Revoluci\u00f3n de Octubre brill\u00f3 en los cinco continentes, despertando a millones de oprimidos y explotados de todo el mundo. Nunca en la historia de la humanidad ha existido una revoluci\u00f3n de tal importancia y envergadura\u00bb.<\/p>\n\n\n\n<p>Por \u00faltimo, Lenin dedic\u00f3 el per\u00edodo de 1893 a 1917 al estudio de las limitaciones del partido del viejo tipo, es decir, el partido socialdem\u00f3crata. El texto de Lenin, \u00abNuestro programa\u00bb, destaca la necesidad de que el partido participe en una actividad continua y no dependa de brotes espont\u00e1neos o iniciales [stikhiinyi]. Esta actividad continua pondr\u00eda al partido en contacto \u00edntimo y org\u00e1nico con la clase obrera y el campesinado, fomentando as\u00ed el crecimiento de protestas que podr\u00edan adquirir un car\u00e1cter masivo. Fue esta consideraci\u00f3n la que llev\u00f3 a Lenin a elaborar su concepci\u00f3n del partido revolucionario en \u00ab\u00bfQu\u00e9 hacer?\u00bb (1902). Esta destacada intervenci\u00f3n subray\u00f3 el papel de los obreros con conciencia de clase como vanguardia del partido y la importancia de la agitaci\u00f3n pol\u00edtica entre los obreros para desarrollar una conciencia pol\u00edtica genuinamente poderosa contra toda tiran\u00eda y opresi\u00f3n. Lenin argumentaba que los trabajadores necesitan sentir la intensidad de la brutalidad del sistema y comprender la importancia de la solidaridad.<\/p>\n\n\n\n<p>Estos textos, abarcando desde 1896 hasta 1916, prepararon el terreno para que los bolcheviques y Lenin comprendieran c\u00f3mo actuar durante las luchas de 1917. Es un indicador de la confianza de Lenin en las masas y en su teor\u00eda el hecho de que escribiera su audaz panfleto \u00ab\u00bfPueden los bolcheviques conservar el poder del Estado?\u00bb unas semanas antes de la toma del poder.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>LA CONSTRUCCI\u00d3N DE UN ESTADO<\/strong><\/h6>\n\n\n\n<p>Despu\u00e9s de la victoria, Lenin se encontr\u00f3 con los desaf\u00edos de construir un proyecto socialista en el antiguo Imperio zarista, devastado por la avaricia y la guerra. Antes de que los soviets tuvieran la oportunidad de organizarse, los imperialistas atacaron desde todas las direcciones. Las intervenciones directas en apoyo a campesinos, obreros y minor\u00edas nacionales impidieron deserciones masivas de la nueva Revoluci\u00f3n a los ej\u00e9rcitos contrarrevolucionarios. A pesar de sus limitados recursos, los campesinos resistieron en el nuevo comienzo. Sin embargo, la pregunta persist\u00eda: \u00bfc\u00f3mo se construye el socialismo en un pa\u00eds empobrecido, con un desarrollo social obstaculizado por la autocracia zarista?<\/p>\n\n\n\n<p>Una lectura cuidadosa de \u00abEstado y Revoluci\u00f3n\u00bb (1918) anticipa los desaf\u00edos que enfrentar\u00edan los soviets en su nueva tarea: no solo heredar la estructura del Estado, sino tambi\u00e9n \u00abdestruir el Estado\u00bb, construir un nuevo conjunto de instituciones y una nueva cultura institucional, y fomentar una nueva actitud de los cuadros hacia el Estado y la sociedad. En \u00abLas tareas inmediatas del gobierno sovi\u00e9tico\u00bb (abril de 1918), Lenin resume los trabajos de los primeros meses, mostrando que los sovi\u00e9ticos eran plenamente conscientes de los profundos problemas que deb\u00edan abordar. Su revoluci\u00f3n no tuvo lugar en un pa\u00eds capitalista avanzado, sino en lo que Marx llam\u00f3 el \u00abreino de la escasez\u00bb. Aumentar las fuerzas productivas y socializar simult\u00e1neamente los medios de producci\u00f3n fue una tarea de inmensas proporciones.<\/p>\n\n\n\n<p>\u00abSin alfabetizaci\u00f3n\u00bb, escribi\u00f3 Lenin, \u00abno puede haber pol\u00edtica. Solo puede haber rumores, cotilleos y prejuicios\u00bb. Los limitados recursos del Estado sovi\u00e9tico se dirigieron a la alfabetizaci\u00f3n, y los cuadros del Partido se esforzaron por revertir el hecho de que solo un tercio de los hombres y menos de una quinta parte de las mujeres estaban alfabetizados. A trav\u00e9s de la campa\u00f1a de Likbez y la pol\u00edtica de indigenizaci\u00f3n (korenizatsiya), los sovi\u00e9ticos lograron, en dos d\u00e9cadas, aumentar los niveles de alfabetizaci\u00f3n al 86% para los hombres y al 65% para las mujeres. A menudo se olvida la importancia de los obreros y campesinos en la construcci\u00f3n de la Rusia sovi\u00e9tica (Mija\u00edl Kalinin proven\u00eda de una familia de campesinos; Jos\u00e9 Stalin, de una familia de zapateros y criadas). La educaci\u00f3n, la salud, la vivienda, el control de la econom\u00eda, las actividades culturales y el desarrollo social fueron el n\u00facleo del trabajo de la nueva Rusia sovi\u00e9tica, dirigida por Lenin. Ninguna cr\u00edtica sin fundamento sobre la Uni\u00f3n Sovi\u00e9tica puede borrar el inmenso logro de este Estado obrero.<\/p>\n\n\n\n<p>En el \u00faltimo a\u00f1o de su vida, Lenin escribi\u00f3 cuatro textos formidables: &#8216;Sobre la cooperaci\u00f3n&#8217;, &#8216;Nuestra revoluci\u00f3n&#8217;, &#8216;C\u00f3mo debemos reordenar la inspecci\u00f3n obrera y campesina&#8217; y &#8216;Mejor menos, pero mejor&#8217;. En estos textos, Lenin reconoci\u00f3 las dificultades del proceso de transformaci\u00f3n del capitalismo en socialismo. Escribi\u00f3 sobre la \u00abenorme e ilimitada importancia\u00bb de las sociedades cooperativas, la necesidad de reconstruir la base productiva y de construir sociedades para fomentar la confianza de las masas. Lo que Lenin indic\u00f3 fue la necesidad de una transformaci\u00f3n cultural, una nueva forma de vida para los trabajadores y los campesinos, y formas nuevas y creativas para que tengan poder sobre su sociedad y construyan claridad en la acci\u00f3n. Los trabajadores han heredado la arquitectura de un estado espantoso, y esto debe ser totalmente transformado. \u00bfPero c\u00f3mo? La reflexi\u00f3n de Lenin en \u00abMejor menos, pero mejor\u00bb es ferozmente honesta:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>\u00ab\u00bfQu\u00e9 elementos tenemos para construir este aparato? Solo dos. Primero, los obreros que est\u00e1n absortos en la lucha del socialismo. Estos elementos no est\u00e1n suficientemente instruidos. Les gustar\u00eda construir un aparato mejor para nosotros, pero no saben c\u00f3mo. No pueden construirlo. A\u00fan no han desarrollado la cultura necesaria para ello; y es cultura lo que se necesita. No se conseguir\u00e1 nada en esto haciendo las cosas con prisas, por asalto, por \u00edmpetu o vigor, o en general, por cualquiera de las mejores cualidades humanas. En segundo lugar, tenemos elementos de conocimiento, educaci\u00f3n y formaci\u00f3n, pero son rid\u00edculamente insuficientes en comparaci\u00f3n con todos los dem\u00e1s pa\u00edses\u00bb.<\/em><\/p>\n<\/blockquote>\n\n\n\n<p>En su \u00faltima aparici\u00f3n p\u00fablica en el Soviet de Mosc\u00fa en noviembre de 1922, Lenin elogi\u00f3 los logros de la joven Rep\u00fablica Sovi\u00e9tica, pero tambi\u00e9n advirti\u00f3 sobre el duro camino a seguir. Nuestro Partido, dijo, \u00abun peque\u00f1o grupo de personas en comparaci\u00f3n con la poblaci\u00f3n total del pa\u00eds, ha acometido esta tarea. Este peque\u00f1o n\u00facleo se ha impuesto la tarea de rehacerlo todo, y lo har\u00e1. Pero esta tarea no es solo del Partido, sino de los obreros y campesinos, que ven el nuevo aparato sovi\u00e9tico como algo suyo. Hemos llevado el socialismo a la vida cotidiana y debemos ver c\u00f3mo est\u00e1n las cosas. Esa es la tarea de nuestros d\u00edas, la tarea de nuestra \u00e9poca\u00bb. La Uni\u00f3n Sovi\u00e9tica solo dur\u00f3 setenta y cuatro a\u00f1os, pero en esos a\u00f1os experiment\u00f3 ferozmente para superar la miseria del capitalismo. Setenta y cuatro a\u00f1os es la esperanza de vida media mundial. Sencillamente, no hubo tiempo suficiente para hacer avanzar la agenda socialista antes de que la URSS fuera destruida. Pero el legado de Lenin no est\u00e1 solo en la URSS. Est\u00e1 en la lucha global por trascender los dilemas a los que se enfrenta la humanidad avanzando hacia el socialismo.<\/p>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>El 21 de enero conmemoramos la siembra de Vladimir Lenin, un l\u00edder visionario cuya huella indeleble en la historia sigue inspirando la lucha por la justicia, la igualdad y el socialismo.<\/p>\n","protected":false},"author":3,"featured_media":4748,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[159],"tags":[151,52],"class_list":["post-4761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles","tag-anticapitalismo","tag-antiimperialismo"],"blocksy_meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/posts\/4761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/comments?post=4761"}],"version-history":[{"count":1,"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/posts\/4761\/revisions"}],"predecessor-version":[{"id":7085,"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/posts\/4761\/revisions\/7085"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/media\/4748"}],"wp:attachment":[{"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/media?parent=4761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/categories?post=4761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/tags?post=4761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}