{"id":989,"date":"2026-01-26T15:45:56","date_gmt":"2026-01-26T15:45:56","guid":{"rendered":"https:\/\/ipa-aip.org\/plataforma-politica\/"},"modified":"2026-04-20T18:59:54","modified_gmt":"2026-04-20T18:59:54","slug":"plataforma-politica","status":"publish","type":"page","link":"https:\/\/ipa-aip.org\/es\/plataforma-politica\/","title":{"rendered":"Plataforma Pol\u00edtica"},"content":{"rendered":"\n<div class=\"wp-block-group alignfull has-palette-color-2-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:0px;margin-bottom:0px;padding-top:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--10)\">\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-995f960e wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center pos-relative political-platform-left is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-palette-color-8-color has-text-color has-link-color has-aip-font-size wp-elements-17b875dc3e63c0afa5fe95ff723b8500\" style=\"font-style:normal;font-weight:1000;line-height:1\">PLATAFORMA<br>POLITICA<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-container-core-column-is-layout-985685b5 wp-block-column-is-layout-flow\" style=\"padding-top:0;padding-bottom:0\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"526\" height=\"597\" src=\"https:\/\/ipa-aip.org\/wp-content\/uploads\/2026\/01\/circle.webp\" alt=\"\" class=\"wp-image-246\" srcset=\"https:\/\/ipa-aip.org\/wp-content\/uploads\/2026\/01\/circle.webp 526w, https:\/\/ipa-aip.org\/wp-content\/uploads\/2026\/01\/circle-264x300.webp 264w\" sizes=\"auto, (max-width: 526px) 100vw, 526px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:0px;margin-bottom:0px;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group regions-buttons is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe0a7de2 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button pill\"><a class=\"wp-block-button__link has-palette-color-8-color has-palette-color-14-background-color has-text-color has-background has-link-color wp-element-button\" href=\"#section1\">un mundo en crisis<\/a><\/div>\n\n\n\n<div class=\"wp-block-button pill\"><a class=\"wp-block-button__link has-palette-color-4-color has-palette-color-6-background-color has-text-color has-background has-link-color wp-element-button\" href=\"<!--[CDATA[#section2]]--&gt;\">ARTICULACI\u00d3N POPULAR COMO RESPUESTA A LA CRISIS <\/a><\/div>\n\n\n\n<div class=\"wp-block-button pill\"><a class=\"wp-block-button__link has-palette-color-4-color has-palette-color-7-background-color has-text-color has-background has-link-color wp-element-button\" href=\"#section3\">PLATAFORMA PROGRAMATICA<\/a><\/div>\n\n\n\n<div class=\"wp-block-button pill\"><a class=\"wp-block-button__link has-palette-color-4-color has-palette-color-12-background-color has-text-color has-background has-link-color wp-element-button\" href=\"<!--[CDATA[#section4]]--&gt;\">NUESTRA AGENDA EN COMU\u0301N: \u00bfqu\u00e9 hacer?<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull plataform-section is-layout-constrained wp-container-core-group-is-layout-1555f568 wp-block-group-is-layout-constrained\" id=\"section1\" style=\"margin-top:0px;margin-bottom:0px\">\n<div class=\"wp-block-group alignfull overflow-hidden has-palette-color-14-background-color has-background is-layout-constrained wp-container-core-group-is-layout-ecbab5c3 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-6f325671 wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--10);padding-bottom:var(--wp--preset--spacing--10)\">\n<h2 class=\"wp-block-heading has-palette-color-8-color has-text-color has-link-color has-aip-font-size wp-elements-28a863b92e140c1c5d0d5c82b7951209\" style=\"font-style:normal;font-weight:1000;line-height:1\">UN MUNDO EN CRISIS<\/h2>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:600;letter-spacing:-0.42px;line-height:1\">Estamos atravesando un per\u00edodo largo de una crisis estructural y profunda del capitalismo. <\/p>\n\n\n\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">Se trata de una crisis del modo de producci\u00f3n capitalista que ha devenido en una profunda crisis social, por la profundizaci\u00f3n de las desigualdades, aumento de la pobreza, del hambre, de la precarizaci\u00f3n y despojo de derechos laborales a las clases trabajadoras. Estamos atravesando una peligrosa crisis ambiental, por la agresi\u00f3n del capital sobre los bienes naturales y una crisis pol\u00edtica del Estado burgu\u00e9s y de las formas burguesas de democracia.  <\/p>\n<\/div>\n\n\n\n<div id=\"political-platform-float-1\" class=\"wp-block-group float-border-box right-box is-layout-constrained wp-container-core-group-is-layout-3ec51e27 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-palette-color-17-color has-text-color has-link-color has-aip-font-size wp-elements-03656631f869a8a73e1ff3fb77d2b52e\" style=\"font-style:normal;font-weight:1000;line-height:1\">UN MUNDO<br>EN CRISIS<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-palette-color-17-color has-text-color has-link-color has-aip-font-size wp-elements-03656631f869a8a73e1ff3fb77d2b52e\" style=\"font-style:normal;font-weight:1000;line-height:1\">UN MUNDO<br>EN CRISIS<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-palette-color-17-color has-text-color has-link-color has-aip-font-size wp-elements-03656631f869a8a73e1ff3fb77d2b52e\" style=\"font-style:normal;font-weight:1000;line-height:1\">UN MUNDO<br>EN CRISIS<\/h2>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-5-background-color has-background is-layout-constrained wp-container-core-group-is-layout-ecbab5c3 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-content-justification-right is-layout-constrained wp-container-core-group-is-layout-cc43fbaa wp-block-group-is-layout-constrained\">\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">La crisis social del capitalismo se manifiesta en la pauperizaci\u00f3n de las condiciones de vida y de trabajo en todo el mundo. La crisis del empleo se revela en la medida que los trabajos son cada vez menos factibles, y a su vez, los agronegocios capitalistas eliminan a las y los peque\u00f1os agricultores, campesinos y campesinas. El avance tecnol\u00f3gico se pone al servicio de la expulsi\u00f3n de trabajadores y trabajadoras del mundo del trabajo formal en el Norte, mientras potencia y colabora con las formas m\u00e1s aberrantes de precarizaci\u00f3n laboral y explotaci\u00f3n en el Sur.      <\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull overflow-hidden has-palette-color-14-background-color has-background is-layout-constrained wp-container-core-group-is-layout-ecbab5c3 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-c69cce60 wp-block-group-is-layout-constrained\">\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">Esta crisis se ve reflejada en el creciente n\u00famero de personas que enfrentan el hambre y la migraci\u00f3n. <br>Se trata de una crisis energ\u00e9tica, ambiental y de producci\u00f3n de alimentos. Es una crisis que va desde el desalojo de familias campesinas de sus tierras hasta la falta de acceso a la vivienda de las mayor\u00edas populares urbanas. Esta crisis aumenta la precariedad y la pobreza, aumentando la desigualdad en todo el planeta hasta cifras nunca vistas. Hay una crisis de rentabilidad: los capitalistas no consiguen obtener suficientes beneficios con la tendencia del capital a oscilar hacia burbujas de activos de todo tipo, incluyendo las finanzas. Porque el capitalismo est\u00e1 dominado en todo el mundo por el capital financiero, que solo busca el rentismo y la especulaci\u00f3n produciendo cada vez m\u00e1s concentraci\u00f3n de las ganancias y las riquezas. El capitalismo no puede sostenerse a si\u0301 mismo. Su marco pol\u00edtico actual, el neoliberalismo, ha demostrado sus l\u00edmites. La crisis del capitalismo engendra una crisis de valores: un aumento del individualismo y del consumismo, un desprecio por la vida y por la naturaleza.   <\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading float-border-text right has-palette-color-17-color has-text-color has-link-color has-aip-font-size wp-elements-c4e1fa4a0de160d3b1ad8ec884af67da\" id=\"political-platform-float-2\" style=\"font-style:normal;font-weight:1000;line-height:1\">UN MUNDO<br>EN CRISIS<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-5-background-color has-background is-layout-constrained wp-container-core-group-is-layout-ecbab5c3 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-content-justification-right is-layout-constrained wp-container-core-group-is-layout-cc43fbaa wp-block-group-is-layout-constrained\">\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">Es una crisis de la civilizaci\u00f3n occidental y euroc\u00e9ntrica, que se evidencia en el derrumbe de sus instituciones pol\u00edticas y en su forma de Estado liberal, republicano y burgu\u00e9s. Donde las democracias, dentro de su forma representativa y liberal, est\u00e1n fuertemente restringidas para expresar proyectos de transformaciones profundas y radicales que respondan a los problemas del pueblo. En muchos casos, a trav\u00e9s de estrategias de guerra h\u00edbrida, utilizan a grandes sectores de la sociedad para oponerse a los derechos b\u00e1sicos que los pueblos han conquistado. Incluso a la democracia.    <\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading float-border-text has-palette-color-14-color has-text-color has-link-color has-aip-font-size wp-elements-db386fd9d1fb2987eb04aefdeaac631f\" id=\"political-platform-float-3\" style=\"font-style:normal;font-weight:1000;line-height:1\">UN MUNDO<br>EN CRISIS<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull overflow-hidden has-palette-color-14-background-color has-background is-layout-constrained wp-container-core-group-is-layout-ecbab5c3 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-c69cce60 wp-block-group-is-layout-constrained\">\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">El imperialismo estadounidense somete a nuestros pueblos a guerras h\u00edbridas y no convencionales, env\u00eda paquetes de intervenci\u00f3n disfrazados de proyectos humanitarios y de ayuda para el desarrollo, interviene en procesos electorales para asegurar el acceso a nuestros bienes comunes, pretende acoplar nuestros territorios a su sistema reproductor, sanciona y bloquea nuestras soberan\u00edas y resistencias, sujeta nuestras econom\u00edas a deudas ileg\u00edtimas e impagables y niega toda contribuci\u00f3n posible a los problemas fundamentales de nuestros pueblos.  <\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading float-border-text right has-palette-color-17-color has-text-color has-link-color has-aip-font-size wp-elements-f71ad5fcfff12069b64bda41ddaf562c\" id=\"political-platform-float-4\" style=\"font-style:normal;font-weight:1000;line-height:1\">UN MUNDO<br>EN CRISIS<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-5-background-color has-background is-layout-constrained wp-container-core-group-is-layout-ecbab5c3 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-content-justification-right is-layout-constrained wp-container-core-group-is-layout-cc43fbaa wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group pos-relative is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">La tensi\u00f3n a nivel geopol\u00edtico indica una agudizaci\u00f3n de la crisis producto de la disminuci\u00f3n del poder de los Estados Unidos y el ascenso de China. El gigante oriental se est\u00e1 convirtiendo lentamente en una de las econom\u00edas m\u00e1s poderosas del mundo. Las guerras comerciales son una consecuencia de este cambio de poder econ\u00f3mico. Sin embargo, a pesar de estos cambios, Estados Unidos mantiene su hegemon\u00eda militar sobre el mundo. Sigue siendo el pa\u00eds con mayor poder\u00edo militar, aunque su poder ideol\u00f3gico se sigue erosionando. La dominaci\u00f3n no es sin\u00f3nimo de hegemon\u00eda      <br><br>La contradicci\u00f3n entre el desmoronamiento econ\u00f3mico e ideol\u00f3gico de Estados Unidos y su supremac\u00eda militar plantea grandes peligros para el planeta. La pandemia de Covid 19 ha acentuado el surgimiento de China como poder econ\u00f3mico global ante las respuestas incoherentes de las econom\u00edas imperialistas, como Estados Unidos, para sostener a su fuerza de trabajo y su modelo bajo \u201cnuevas normas\u201d que solo producen desempleo masivo.  <\/p>\n\n\n\n<div id=\"political-platform-float-5\" class=\"wp-block-group float-border-box is-layout-constrained wp-container-core-group-is-layout-3ec51e27 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-palette-color-8-color has-text-color has-link-color has-aip-font-size wp-elements-07c450df0a190d531f06334c4558483c\" style=\"font-style:normal;font-weight:1000;line-height:1\">UN MUNDO<br>EN CRISIS<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-14-background-color has-background is-layout-constrained wp-container-core-group-is-layout-ecbab5c3 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<p class=\"wp-block-paragraph\" style=\"font-size:clamp(2.2rem, 2.2rem + ((1vw - 0.2rem) * 2.25), 4rem);line-height:1\">El surgimiento del neofascismo es una forma del gran capital para controlar el Estado, imponiendo gobiernos autoritarios de extrema derecha para cumplir su programa anti-pueblo. Estas formas de gobierno son una grave amenaza para la justicia social.  <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-layout-constrained wp-container-core-group-is-layout-ecbab5c3 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-c69cce60 wp-block-group-is-layout-constrained\">\n<p class=\"has-xl-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:700;letter-spacing:-0.56px;line-height:1;text-transform:uppercase\">El capitalismo es insostenible.  <br>En su actual marco pol\u00edtico, el neoliberalismo ha demostrado sus l\u00edmites. <\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull plataform-section is-layout-constrained wp-container-core-group-is-layout-1555f568 wp-block-group-is-layout-constrained\" id=\"section2\" style=\"margin-top:0px;margin-bottom:0px\">\n<div class=\"wp-block-group alignfull overflow-hidden has-palette-color-6-background-color has-background is-layout-constrained wp-container-core-group-is-layout-ecbab5c3 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-6f325671 wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--10);padding-bottom:var(--wp--preset--spacing--10)\">\n<h2 class=\"wp-block-heading has-palette-color-4-color has-text-color has-link-color has-aip-font-size wp-elements-a7d963c9c9c597e9794a105885398564\" style=\"font-style:normal;font-weight:1000;line-height:1\">ARTICULACI\u00d3N POPULAR COMO RESPUESTA A LA CRISIS <\/h2>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:600;letter-spacing:-0.42px;line-height:1\">Desde hace a\u00f1os se est\u00e1n construyendo nuevas formas de articulaci\u00f3n internacional, en diferentes espacios y diversos continentes. <\/p>\n\n\n\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">En Am\u00e9rica Latina y el Caribe se han forjado las articulaciones de ALBA Movimientos y el Foro de S\u00e3o Paulo. Tambi\u00e9n existen espacios internacionales como la Marcha Mundial de Mujeres (MMM), la V\u00eda Campesina Internacional y otros. <\/p>\n<\/div>\n\n\n\n<div id=\"political-platform-float-6\" class=\"wp-block-group float-border-box right-box is-layout-constrained wp-container-core-group-is-layout-3ec51e27 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-palette-color-18-color has-text-color has-link-color has-aip-font-size wp-elements-0842ad87ec7960462902193bf060175c\" style=\"font-style:normal;font-weight:1000;line-height:1\">ARTICULACI\u00d3N POPULAR COMO RESPUESTA A LA CRISIS<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-palette-color-18-color has-text-color has-link-color has-aip-font-size wp-elements-0842ad87ec7960462902193bf060175c\" style=\"font-style:normal;font-weight:1000;line-height:1\">ARTICULACI\u00d3N POPULAR COMO RESPUESTA A LA CRISIS<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-palette-color-18-color has-text-color has-link-color has-aip-font-size wp-elements-0842ad87ec7960462902193bf060175c\" style=\"font-style:normal;font-weight:1000;line-height:1\">ARTICULACI\u00d3N POPULAR COMO RESPUESTA A LA CRISIS<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-palette-color-18-color has-text-color has-link-color has-aip-font-size wp-elements-0842ad87ec7960462902193bf060175c\" style=\"font-style:normal;font-weight:1000;line-height:1\">ARTICULACI\u00d3N POPULAR COMO RESPUESTA A LA CRISIS<\/h2>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-5-background-color has-background is-layout-constrained wp-container-core-group-is-layout-ecbab5c3 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-content-justification-right is-layout-constrained wp-container-core-group-is-layout-cc43fbaa wp-block-group-is-layout-constrained\">\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">En \u00c1frica, la Conferencia Pan Africanism Today (Panafricanismo Hoy), que tuvo lugar en Lusaka en 2016 ha sentado las bases para construir una fuerte unidad en todo el continente, que es ideol\u00f3gicamente clara en los valores y la praxis socialistas. Esto condujo al desarrollo de m\u00faltiples procesos de formaci\u00f3n pol\u00edtica, los \u00e9xitos de las Conferencias Panafricanismo Hoy en T\u00fanez (2017) y Ghana (2018). La regi\u00f3n ha visto un r\u00e1pido crecimiento de los esfuerzos coordinados para luchar contra el imperialismo y construir un panafricanismo socialista.   <\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-6-background-color has-background is-layout-constrained wp-container-core-group-is-layout-ecbab5c3 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-c69cce60 wp-block-group-is-layout-constrained\">\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">Desde hace a\u00f1os estamos confluyendo esos esfuerzos hacia una articulaci\u00f3n que hemos llamado la <strong>Asamblea Internacional de los Pueblos<\/strong>, como una forma de articular todos los espacios internacionales, todas las formas de organizaci\u00f3n de nuestros pueblos, sin que esto implique sustituir a nadie. <\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-5-background-color has-background is-layout-constrained wp-container-core-group-is-layout-ecbab5c3 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<p class=\"wp-block-paragraph\" style=\"font-size:clamp(2.2rem, 2.2rem + ((1vw - 0.2rem) * 2.25), 4rem);line-height:1\">De ah\u00ed que, junto con el proceso de articulaci\u00f3n de organizaciones locales, nacionales y regionales, estamos construyendo una plataforma pol\u00edtica com\u00fan que nos ayude a enfrentar los dilemas de la humanidad y la crisis del capitalismo.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-6-background-color has-background is-content-justification-center is-layout-constrained wp-container-core-group-is-layout-4e4f8700 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--50);padding-bottom:var(--wp--preset--spacing--50)\">\n<div class=\"wp-block-group is-content-justification-right is-layout-constrained wp-container-core-group-is-layout-cc43fbaa wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group pos-relative is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-medium-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:600;line-height:1\">Ese proceso de discusi\u00f3n es din\u00e1mico, porque las contradicciones y las correlaciones de fuerzas lo son, y eso nos obliga a ir actualizando los temas y nuestra plataforma pol\u00edtica. De all\u00ed, que este documento es un instrumento de construcci\u00f3n de unidad pol\u00edtica, program\u00e1tica e ideol\u00f3gica que se va modificando con el tiempo sobre la base de la lucha de clases. Por eso, no se lo puede tomar como un documento final, sino como una base para el debate y la convergencia de ideas. Esperamos que todos y todas sigamos debatiendo este material con nuestras bases sociales, nuestros movimientos y organizaciones en todos los pa\u00edses.    <\/p>\n\n\n\n<div id=\"political-platform-float-7\" class=\"wp-block-group float-border-box is-layout-constrained wp-container-core-group-is-layout-3ec51e27 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-palette-color-18-color has-text-color has-link-color has-aip-font-size wp-elements-0842ad87ec7960462902193bf060175c\" style=\"font-style:normal;font-weight:1000;line-height:1\">ARTICULACI\u00d3N POPULAR COMO RESPUESTA A LA CRISIS<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull plataform-section is-layout-constrained wp-container-core-group-is-layout-1555f568 wp-block-group-is-layout-constrained\" id=\"section3\" style=\"margin-top:0px;margin-bottom:0px\">\n<div class=\"wp-block-group alignfull has-palette-color-7-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<h2 class=\"wp-block-heading has-text-align-center has-palette-color-4-color has-text-color has-link-color has-aip-font-size wp-elements-f80d59d901b411d4eacfa56034c7fa83\" style=\"font-style:normal;font-weight:1000;line-height:1\">PLATAFORMA PROGRAMATICA<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:600;line-height:1\">Mira el contenido o haz click en el bot\u00f3n para descargar el PDF<\/p>\n\n\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-7-background-color has-background is-layout-constrained wp-container-core-group-is-layout-4523050a wp-block-group-is-layout-constrained\" style=\"padding-top:0px;padding-bottom:10rem\">\n<div class=\"wp-block-group has-border-color has-palette-color-2-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-2-background-color has-background has-medium-font-size wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\">Por una lucha anticapitalista y una nueva forma de organizar la sociedad en nuestros pa\u00edses<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El modo de producci\u00f3n capitalista ya no es sin\u00f3nimo de progreso. No es soluci\u00f3n para los problemas del pueblo, como son el garantizar el trabajo, la tierra, la educaci\u00f3n, la vivienda y la igualdad social. Al contrario, es un sistema del pasado que solo concentra riquezas y promueve la desigualdad y las injusticias sociales. Por ello, la AIP lucha para derribar este sistema y generar las condiciones para que se adopte un nuevo modo de producci\u00f3n pos capitalista, de acuerdo con las condiciones objetivas (fuerzas productivas existentes) y las condiciones subjetivas (capacidad de organizaci\u00f3n popular). Cada pueblo a su tiempo sabr\u00e1 c\u00f3mo nombrarlo, si es socialismo, liberaci\u00f3n nacional o buen vivir. Lo importante es que sea un sistema basado en la b\u00fasqueda de igualdad social, la justicia y la solidaridad entre todos, eliminando la explotaci\u00f3n de lxs trabajadorxs y la Madre Tierra.       <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-6-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-6-background-color has-background has-medium-font-size wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\">Lucha antiimperialista, anticolonial y antisionista por la soberan\u00eda de los pueblos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este contexto de crisis, las fuerzas del capital imperialista aumentan su ofensiva en contra de los pueblos y lxs trabajadorxs. Por eso, avanzan sobre los recursos naturales, como el petr\u00f3leo, las tierras, los recursos minerales, el agua y la biodiversidad.<br>  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para ello, se utilizan todas las formas pol\u00edticas e ideol\u00f3gicas posibles, resumidas en lo que se denomina \u201cestrategia de guerras h\u00edbridas\u201d, profundizando ataques coloniales y sionistas, en el caso del mundo \u00e1rabe. Estas guerras no carecen de motivos para el gran capital. Las empresas transnacionales siguen a los tanques, tomando posesi\u00f3n de territorios para extraer materias primas, obligando a los pueblos a utilizar los bienes y servicios producidos por las mismas empresas transnacionales. Las bases militares de las potencias imperialistas se instalan en lugares geoestrat\u00e9gicos para mantener el poder de las corporaciones y de la clase dominante.      <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debemos luchar por la autodeterminaci\u00f3n, soberan\u00eda e independencia de nuestros pueblos en la construcci\u00f3n de su propio destino y blindar a nuestras regiones como lugares de paz, sin la intervenci\u00f3n de las fuerzas imperialistas de Estados Unidos, la Uni\u00f3n Europea ni de los instrumentos de guerra multilaterales, como la Organizaci\u00f3n del Tratado del Atl\u00e1ntico Norte (OTAN). <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-10-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-8-color has-palette-color-10-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-6820301dbed318462e73893c0344a825 wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha por un feminismo de clase y popular<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El feminismo anticapitalista denuncia que el patriarcado no s\u00f3lo act\u00faa a nivel cultural e ideol\u00f3gico, sino que forma parte de la base estructural del sistema actual, que necesita de las desigualdades de clase, g\u00e9nero y raza para obtener beneficios econ\u00f3micos. La alianza entre el capitalismo y el patriarcado ha sido fundamental para el desarrollo de un sistema que invisibiliza la misma reproducci\u00f3n de la vida que lo sustenta. Luchamos por un mundo que ponga la vida en el centro, que parta de la interdependencia de los seres humanos y sus vulnerabilidades hacia la sostenibilidad de la vida y la corresponsabilidad de los cuidados con los varones y el Estado.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Denunciamos que para eso se impuso un modelo de familia heterosexual y heteronormativa que impide a las personas el libre ejercicio de su sexualidad y de su identidad de g\u00e9nero. Nuestra lucha es tambi\u00e9n para cambiar ese orden simb\u00f3lico e ideol\u00f3gico que sostiene la visi\u00f3n de inferioridad de las mujeres y superioridad de los varones. La lucha feminista ha propuesto una reconceptualizaci\u00f3n, que reconozca el aporte de las mujeres al conjunto de la sociedad y ha reivindicado cambios para una sociedad con libertad, igualdad y diversidad.    <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las desigualdades de las mujeres se expresan a trav\u00e9s de una realidad material llena de violencias machistas (asesinatos, violencia de g\u00e9nero, violencias sexuales, violencia institucional), de falta de derechos (sexuales y reproductivos, acceso a la propiedad, a la educaci\u00f3n) y de precariedad econ\u00f3mica (doble explotaci\u00f3n, brecha laboral, feminizaci\u00f3n de la pobreza, trabajos no remunerados) Nuestra lucha tambi\u00e9n es la lucha contra todas las violencias machistas y contra la explotaci\u00f3n de todas las mujeres. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La lucha contra el sistema patriarcal y por una sociedad igualitaria es una lucha de primer orden para construir nuestros proyectos emancipatorios. Actualmente una nueva ola de movilizaciones recorre el mundo y es la ola feminista protagonizada por millones de mujeres: una de las luchas m\u00e1s din\u00e1micas, masivas y mejor articuladas en el plano internacional.  <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-1-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-8-color has-palette-color-1-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-9c3796aba4460d231d3d3f2272a3b09f wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha antirracista y contra la discriminaci\u00f3n racial<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirmamos que el capitalismo se ha desarrollado sobre la base de la supremac\u00eda blanca y el racismo como principios para imponer y justificar su dominaci\u00f3n y opresi\u00f3n, la acumulaci\u00f3n de capital y la divisi\u00f3n de la clase trabajadora. La lucha contra el racismo, la discriminaci\u00f3n racial, la xenofobia y la intolerancia, es un componente fundamental de nuestra lucha contra el capitalismo y por el internacionalismo y una condici\u00f3n previa para la unidad de la clase trabajadora.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reafirmamos y defendemos el derecho de todo pueblo a tener sus tierras, territorios, su idioma, su religi\u00f3n, cultivar y desarrollar su cosmovisi\u00f3n, identidad, cultura, sistemas productivos y su autonom\u00eda social y pol\u00edtica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reconocemos que el respeto a la dignidad, derechos y diversidad de pueblos, culturas y poblaciones es fundamental para construir la solidaridad entre los pueblos y luchamos contra cualquier manifestaci\u00f3n de racismo, xenofobia, discriminaci\u00f3n nacional o \u00e9tnica, cultural o por el color de la piel.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-16-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-8-color has-palette-color-16-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-4b3938a8c8c1bbc6e5896ed4e068ed69 wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>La naturaleza del estado burgu\u00e9s y su fracaso<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El modelo de Estado, que funciona organizado desde la consolidaci\u00f3n del capitalismo industrial y de los Estados-naci\u00f3n, est\u00e1 obsoleto, no funciona. Los tres poderes independientes que se hab\u00edan propuesto, el ejecutivo, legislativo y judicial, caen rendidos ante el poder econ\u00f3mico transnacional. La legitimidad del sistema democr\u00e1tico era que el voto de cada ciudadano podr\u00eda dirigir y en todo caso cambiar el rumbo de las decisiones de c\u00f3mo gobernar el Estado. Ahora ya no es as\u00ed. El Estado fue tomado por asalto por el gran capital con su base financiera e internacional. Y por eso, el Estado s\u00f3lo atiende los intereses del capital, garantizando su reproducci\u00f3n y acumulaci\u00f3n. En detrimento de esto, el Estado ya no resuelve los problemas b\u00e1sicos de la poblaci\u00f3n.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso, tenemos que debatir y proponer nuevas formas de funcionamiento y organizaci\u00f3n del Estado para que de hecho represente los intereses del pueblo, de las mayor\u00edas y act\u00fae controlando y regulando las ganancias de los capitalistas. En cada pa\u00eds las fuerzas populares deben construir propuestas de nuevas formas de funcionamiento del Estado que prioricen la expresi\u00f3n del poder popular.   <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-9-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-8-color has-palette-color-9-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-20ab169305e6cf3976ef613053f3a24b wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha por una nueva democracia popular<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Estados republicanos y las democracias liberales que surgieron despu\u00e9s de la Revoluci\u00f3n Francesa, y que se consolidaron durante el siglo XX, ya no funcionan, como tampoco sus instituciones liberales. Hoy, el poder econ\u00f3mico en articulaci\u00f3n con el poder judicial y los medios de comunicaci\u00f3n han hecho que la institucionalidad liberal funcione totalmente como su instrumento. Los medios de comunicaci\u00f3n controlados por las empresas dan forma y manipulan la opini\u00f3n popular, eludiendo la raz\u00f3n y los hechos. La demagogia eclipsa la democracia. El voto de los pueblos, cuando eligen proyectos populares o alternativos al capitalismo, no se respeta. Pero cuando en las urnas ganan los proyectos ultraderechistas, la democracia se convierte en la principal bandera. La democracia, que en muchos pa\u00edses se logr\u00f3 a fuerza de luchas, en la actualidad debe trascender sus l\u00edmites de la institucionalidad liberal y republicana para resolver los problemas estructurales.     <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy, la democracia no logra ser un mecanismo para cambiar y resolver los problemas estructurales. Debemos denunciar el funcionamiento de estas democracias colapsadas y avanzar en la construcci\u00f3n de democracias populares. Tenemos que construir nuevas propuestas de participaci\u00f3n popular en la pol\u00edtica, con nuevas plataformas que se construyan mediante el di\u00e1logo y el debate en torno a la raz\u00f3n y no al miedo, a la esperanza y no al odio. Debemos tener formas concretas de participaci\u00f3n del pueblo en todos los espacios de poder pol\u00edtico de la sociedad, ya sea el ejecutivo, el legislativo y el judicial. El poder s\u00f3lo tiene legitimidad si el pueblo en su mayor\u00eda participa de sus instancias.    <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-11-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-8-color has-palette-color-11-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-83722e5b14397c1a42cb5160b36dd2e3 wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha por la defensa de los recursos naturales como bienes comunes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La crisis internacional ha reforzado la arremetida del poder econ\u00f3mico concentrado en la apropiaci\u00f3n y explotaci\u00f3n de los recursos naturales para mantener sus tasas de ganancia, expulsar a la gente de las tierras que albergan recursos preciosos y a explotar la naturaleza m\u00e1s all\u00e1 de cualquier l\u00edmite racional. Las guerras por el petr\u00f3leo y por las tierras forestales, las guerras por los minerales de tierras raras y por las fuentes de agua son un frente de nuestras batallas actuales.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La agresi\u00f3n del capital a los recursos naturales es la causa de la crisis ambiental que estamos viviendo, que trae como consecuencia cr\u00edmenes ambientales, cambios clim\u00e1ticos, escasez de agua, de tierra, poniendo en riesgo la vida en el mar y en todo el planeta. Estas crisis ambientales afectan de manera desproporcionada a las personas m\u00e1s vulnerables y pobres. La biodiversidad destruida por los intereses capitalistas deja a los pueblos ind\u00edgenas m\u00e1s vulnerables a la degradaci\u00f3n de su entorno natural.    <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debemos defender la soberan\u00eda nacional de nuestros pueblos contra los avances de las empresas transnacionales. Debemos defender nuestra biodiversidad, nuestra tierra, nuestra agua contra la forma aniquiladora del capitalismo. Los bienes de la naturaleza deben ser explotados en equilibrio con la reproducci\u00f3n del ecosistema y al servicio de las necesidades del pueblo. Para eso, el Estado debe ejercer su control con participaci\u00f3n popular de quienes viven en esos territorios.    <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-12-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-12-background-color has-background has-medium-font-size wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha por la reforma agraria popular<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En todo el mundo hay una lucha permanente entre dos modelos de producci\u00f3n agr\u00edcola. De un lado, el modelo del capital y su agronegocio, que impone grandes latifundios, el uso intensivo de pesticidas, agroqu\u00edmicos, mecanizaci\u00f3n, con monocultivo y expulsi\u00f3n de la mano de obra. Del otro lado, el modelo de soberan\u00eda alimentaria que prioriza la organizaci\u00f3n de la producci\u00f3n para producir alimentos (y no solo mercanc\u00edas\/commodities), con tierra para lxs campesinxs, respetando los bienes de la naturaleza y la biodiversidad. Por eso defendemos una reforma agraria de nuevo tipo, que garantice tierra y trabajo a todos quienes quieran vivir en el campo. Que tenga como prioridad la tierra como funci\u00f3n social, la producci\u00f3n de alimentos sanos para todo el pueblo, la adopci\u00f3n de la agroecolog\u00eda como nuevo paradigma que garantiza producir en equilibrio con la naturaleza.<br>A su vez, debemos organizar agroindustrias en forma cooperativa y generar empleo para lxs j\u00f3venes, donde incluso se estimulen otras profesiones. Adem\u00e1s, debemos poner en valor la educaci\u00f3n y la cultura para que est\u00e9 presente en todas las comunidades del medio rural. Defender nuestra comida, nuestra cocina y la soberan\u00eda alimentaria que es el principio de todo el pueblo. En cada pa\u00eds, tenemos el derecho y el deber de producir todos los alimentos necesarios para la supervivencia. El comercio agr\u00edcola internacional no puede desarrollarse sobre la base de las <em>commodities<\/em> controladas por pocas corporaciones transnacionales, sino que debe ser sobre el intercambio justo de los excedentes que haya en cada pa\u00eds.           <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-6-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-6-background-color has-background has-medium-font-size wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha por el control y estatizaci\u00f3n del sistema financiero, los para\u00edsos fiscales y las empresas transnacionales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vivimos un tiempo hist\u00f3rico en que el capitalismo est\u00e1 dominado por el capital financiero y grandes corporaciones transnacionales, que controlan la producci\u00f3n y el comercio mundial y a su vez, nuestros pueblos son sometidos a una deuda ilegal, ileg\u00edtima e impagable que desconoce siglos de saqueo y desposesi\u00f3n. Menos de 500 empresas y bancos dominan la mayor parte de la producci\u00f3n, el comercio y los dep\u00f3sitos bancarios. Pero no generan empleo ni bienestar para los pueblos. Por eso, defendemos como medida de transici\u00f3n para combatir el oligopolio, la concentraci\u00f3n de riqueza y el poder econ\u00f3mico transnacional, la estatizaci\u00f3n de todo sistema financiero. La defensa de una nueva moneda internacional controlada por todos los pa\u00edses y no m\u00e1s el d\u00f3lar ni el euro.     <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Defendemos la abolici\u00f3n de todos los para\u00edsos fiscales y de la deuda externa de los pa\u00edses del Sur global, as\u00ed como el control del capital ficticio. El ahorro que hay en forma de dinero en nuestros pa\u00edses debe ser invertido en la producci\u00f3n de bienes para atender las necesidades de todo el pueblo.  <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-16-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-8-color has-palette-color-16-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-b3e6adc213ddcab69f64843d66dacb2f wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha por el derecho al trabajo para todos, con derechos laborales y salarios dignos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Defendemos que todxs lxs trabajadorxs tengan derecho al trabajo, con sueldo digno y derechos sociales, que garanticen su salud, sus vacaciones y el futuro de su familia. El trabajo dom\u00e9stico y de cuidado pesa sobre la vida de las mujeres, se invisibiliza y desconoce en una l\u00f3gica patriarcal de organizaci\u00f3n de la vida enfocada a la concentraci\u00f3n del capital. Necesitamos poner la vida y el cuidado en el centro.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Defendemos que se desarrolle la solidaridad entre todos los trabajadores del mundo, como una forma esencial de vida y de lucha contra los explotadores que ahora son internacionales. Nunca antes estuvo tan presente la consigna: \u00ab\u00a1Trabajadorxs de todo el mundo, un\u00edos!\u00bb  <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-9-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-8-color has-palette-color-9-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-e78efec25b55ccf1d1d3791e2290d3e1 wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha por los derechos sociales y los derechos humanos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ofensiva del poder econ\u00f3mico concentrado obliga a los Estados a priorizar sus inversiones en pagos de intereses y en proyectos que solo interesan al capital. Para ello, los gobiernos controlan las pol\u00edticas p\u00fablicas de forma que dejan de lado la promoci\u00f3n de los derechos sociales y laborales. La consecuencia es que, en la mayor\u00eda de los pa\u00edses del mundo, han disminuido los servicios p\u00fablicos de atenci\u00f3n sanitaria, la educaci\u00f3n, la atenci\u00f3n a las personas discapacitadas, entre otros. Hay una tendencia a privatizar los servicios p\u00fablicos para transformarlos en mercanc\u00edas. Los derechos pasan a ser mercanc\u00edas, y s\u00f3lo pueden acceder a ellas quienes tienen dinero.     <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Defendemos que toda persona, en todos los pa\u00edses del mundo, tenga derecho a trabajar, a la vivienda, a la tierra, al sueldo digno, a la comida, a la cultura y la recreaci\u00f3n, a la salud y la educaci\u00f3n como derechos universales de todo ser humano.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-1-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-8-color has-palette-color-1-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-12e786e238106edde97f4ed3fa9211ad wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha por el derecho a la educaci\u00f3n y la soberan\u00eda del conocimiento<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El conocimiento es un patrimonio de la humanidad. El conocimiento es cada vez m\u00e1s condici\u00f3n de libertad y de dignidad humana. La forma de democratizar el acceso y la producci\u00f3n de conocimiento no puede seguir quedando en el Norte global. Los pueblos debemos defender la soberan\u00eda cient\u00edfica y tecnol\u00f3gica. Defendemos que todas las personas, independientemente de su edad y condici\u00f3n social, tengan derecho a acceder a la educaci\u00f3n de forma p\u00fablica y gratuita. Pero tambi\u00e9n debemos generar una educaci\u00f3n cr\u00edtica, que no reproduzca un esquema colonial, euroc\u00e9ntrico, racista, elitista y patriarcal. La educaci\u00f3n debe incorporar y respetar los saberes populares, la cultura popular, la historia de lxs vencidxs. Porque la educaci\u00f3n sin un cambio de paradigma de pensamiento seguir\u00e1 reproduciendo las matrices culturales de dominaci\u00f3n y opresi\u00f3n.     <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La transformaci\u00f3n social requiere que repensemos la educaci\u00f3n para que no est\u00e9 al servicio del capital, formando personas d\u00f3ciles con valores neoliberales cuyas habilidades sirvan al mercado y donde las ciencias humanas, las artes y la filosof\u00eda no tengan cabida. Insistimos en una educaci\u00f3n para la emancipaci\u00f3n, con valores democr\u00e1ticos e igualitarios. La educaci\u00f3n tiene que proporcionar habilidades, pero tambi\u00e9n trabajar contra el odio, el racismo, la xenofobia y el machismo. Debemos construir un sistema p\u00fablico y universal de educaci\u00f3n equipado con suficientes recursos materiales y humanos.    <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-11-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-8-color has-palette-color-11-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-79820f7640c7f0dc071b98d9424bce79 wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha por los derechos de las personas de las diversidades sexuales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diversidad sexual y de g\u00e9nero, son una realidad en todos los pa\u00edses y sociedades, como parte de la naturaleza del ser humano. Por eso defendimos el derecho a la autodeterminaci\u00f3n de las personas y poblaciones LGBTI, as\u00ed como debemos combatir la discriminaci\u00f3n social, denunciar la violencia, la intolerancia y la exclusi\u00f3n que sufren.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto implica la ruptura con el modelo patricarcal-heteronormativo de la sexualidad y la familia heterosexual como \u00fanica es parte de la lucha para eliminar los pilares de explotaci\u00f3n-dominaci\u00f3n de la sociedad actual.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-12-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-12-background-color has-background has-medium-font-size wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha por los derechos de migrantes, refugiadxs, poblaciones en di\u00e1sporas, pueblos ind\u00edgenas y todxs aquellxs que son especialmente vulnerables en nuestras sociedades<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La crisis del capitalismo y de la humanidad ha puesto en marcha un \u00e9xodo de decenas de millones de personas de sus hogares y de sus familias. Huyen de la guerra y el hambre hacia una vida mejor. Algunos se dejan llevar por el sue\u00f1o de la felicidad \u201coccidental\u201d, deseosos de ir a Europa o a Am\u00e9rica del Norte. A medida que estos pa\u00edses se promueven a s\u00ed mismos como superiores a otros, refuerzan las barreras para impedir la entrada de las personas desplazadas \u2013un muro en la frontera entre EE. UU. y M\u00e9xico, un conjunto de puestos militares en la regi\u00f3n del Sahel en \u00c1frica. En estos pa\u00edses se promueve la xenofobia contra lxs migrantes y refugiadxs, a los que se culpa \u2013 falsamente\u2013 de los problemas de desigualdad, desempleo y hambre. En las sociedades de todo el mundo, formas de jerarqu\u00eda \u2013contra lxs afrodescendientes en Am\u00e9rica o contra lxs dalits en el sur de Asia\u2013 abaten el alma humana.      <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Defendemos el derecho de todo pueblo a tener su territorio, su idioma, su religi\u00f3n, cultivar su cultura y su autonom\u00eda social y pol\u00edtica. Luchamos contra cualquier discriminaci\u00f3n \u00e9tnica, cultural o por el color de la piel. Defendemos el derecho a la libre circulaci\u00f3n, el derecho de las personas a migrar y a buscar refugio en condiciones de dignidad.   <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-2-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-8-color has-palette-color-2-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-bf239889cf0a33542fe41dd9aedfe87d wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha por la libertad de todxs lxs presxs pol\u00edticxs en el mundo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En toda la historia del capitalismo &#8211; desde su desarrollo en el siglo XIII hasta hoy-, las clases dominantes, los ricos, siempre utilizaron la represi\u00f3n y la persecuci\u00f3n como formas de dominar a lxs explotadxs, impedir su organizaci\u00f3n, perseguir a sus l\u00edderes y, de esa manera, mantener la dominaci\u00f3n. Utilizaron hist\u00f3ricamente el poder del Estado burgu\u00e9s a su servicio, o de milicias privadas.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la actualidad, las clases dominantes utilizan tambi\u00e9n el poder judicial y los medios de comunicaci\u00f3n, para perseguir y desmoralizar a todos los que luchan por la justicia social. Por eso, en la mayor\u00eda de los pa\u00edses, donde hay luchas populares, hay organizaciones del pueblo, muchos l\u00edderes han sufrido persecuciones, asesinatos y encarcelamientos.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Defendemos la libertad inmediata de todos lxs presxs pol\u00edticxs en cualquier pa\u00eds del mundo. A la luz de esto, nos comprometemos a aumentar la visibilidad de la agresi\u00f3n de la clase dominante contra lxs l\u00edderes y activistas del pueblo. Las campa\u00f1as mundiales para poner de relieve esta opresi\u00f3n son muy necesarias y son parte de la lucha anticapitalista, por una democracia popular.   <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-1-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-8-color has-palette-color-1-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-31e9f761f25c44eca38fd8c62acdd44b wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Los espacios de luchas institucionales<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los espacios institucionales ocupados por gobiernos locales y nacionales pueden ser importantes para mejorar las condiciones de vida del pueblo y enfrentar la clase capitalista en ese terreno. Pero desde una perspectiva que ayude a acumular fuerza popular para los cambios estructurales de la sociedad. Podemos y debemos realizar alianzas con partidos y fuerzas que ocupan poderes institucionales, pero manteniendo nuestra autonom\u00eda program\u00e1tica e independencia pol\u00edtica.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No debemos olvidar que los cambios estructurales y anticapitalistas dependen fundamentalmente de la capacidad organizativa y de movilizaci\u00f3n de las masas: de todo el pueblo. Apostamos por la articulaci\u00f3n entre movimientos populares y fuerzas pol\u00edticas fortaleciendo nuestra capacidad de disputar un proyecto de izquierda capaz de construir una sociedad sin opresiones. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-border-color has-palette-color-10-border-color has-palette-color-8-background-color has-background is-layout-constrained wp-container-core-group-is-layout-60db58b5 wp-block-group-is-layout-constrained\" style=\"border-width:12px;border-top-left-radius:12px;border-top-right-radius:12px;border-bottom-left-radius:12px;border-bottom-right-radius:12px;padding-top:var(--wp--preset--spacing--50);padding-right:var(--wp--preset--spacing--20);padding-bottom:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--20)\">\n<p class=\"has-text-align-left programatic-platform-card-title has-palette-color-8-color has-palette-color-10-background-color has-text-color has-background has-link-color has-medium-font-size wp-elements-099e5bbc7ce8408b66f78241afd59d3c wp-block-paragraph\" style=\"padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;font-style:normal;font-weight:600;line-height:1.5\"><strong>Lucha contra el fundamentalismo, el sectarismo y la intolerancia religiosa<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El fundamentalismo y la intolerancia religiosa son instrumentos de divisi\u00f3n y subyugaci\u00f3n de nuestro pueblo. Estas ideolog\u00edas ponen la rigidez en el centro de nuestras sociedades. Nos separan y nos env\u00edan a guerras civiles de un tipo u otro. Estas formas no est\u00e1n solo arraigadas en uno u otro pa\u00eds. Forman parte de movimientos ideol\u00f3gicos internacionales, de derecha, reaccionarios, contra cualquier cambio socioecon\u00f3mico y estimulados por las clases dominantes, como forma de mantener sus privilegios.      <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debemos luchar contra toda discriminaci\u00f3n e intolerancia existentes y contra los fundamentalismos religiosos. Debemos hacer la lucha ideol\u00f3gica permanente, para que se construyan sociedades basadas en la igualdad social, la dignidad y la justicia. <\/p>\n<\/div>\n\n\n\n\n\n<h2 class=\"wp-block-heading float-border-text has-palette-color-19-color has-text-color has-link-color has-aip-font-size wp-elements-68051581c744395413cdb2dd9a55b1fb\" id=\"political-platform-float-9\" style=\"font-style:normal;font-weight:1000;line-height:1\">PLATAFORMA<br>POLITICA<\/h2>\n\n\n\n<h2 class=\"wp-block-heading float-border-text right has-palette-color-19-color has-text-color has-link-color has-aip-font-size wp-elements-04c96750818dde404e0bc8b4d818f24a\" id=\"political-platform-float-8\" style=\"font-style:normal;font-weight:1000;line-height:1\">PLATAFORMA<br>POLITICA<\/h2>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull plataform-section is-layout-constrained wp-container-core-group-is-layout-1555f568 wp-block-group-is-layout-constrained\" id=\"section4\" style=\"margin-top:0px;margin-bottom:0px\">\n<div class=\"wp-block-group alignfull overflow-hidden has-palette-color-12-background-color has-background is-layout-constrained wp-container-core-group-is-layout-5f93b276 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<div class=\"wp-block-group is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-c69cce60 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-black-color has-text-color has-link-color has-aip-font-size wp-elements-6432f86e90607c8e0cffb00650b438f1\" style=\"font-style:normal;font-weight:1000;line-height:1\">NUESTRA AGENDA EN COMU\u0301N:<\/h2>\n\n\n\n<p class=\"has-large-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:600;letter-spacing:-0.42px;line-height:1\">\u00bfqu\u00e9 hacer?<\/p>\n\n\n\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">Vivimos tiempos de incertidumbre sobre el futuro de la humanidad y nuestro planeta. Por lo tanto, los desaf\u00edos son grandes. Nos mueve la esperanza de las m\u00faltiples resistencias que se est\u00e1n desarrollando en todas las latitudes del mundo. Nos fortalecemos con la solidaridad permanente que nuestros pueblos desarrollan todos los d\u00edas frente a las injusticias que genera este sistema.    <\/p>\n<\/div>\n\n\n\n<div id=\"political-platform-float-10\" class=\"wp-block-group float-border-box right-box is-layout-constrained wp-container-core-group-is-layout-3ec51e27 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-palette-color-20-color has-text-color has-link-color has-aip-font-size wp-elements-7a546f6e64cdec812481b2d79c048563\" style=\"font-style:normal;font-weight:1000;line-height:1\">\u00bfqu\u00e9 hacer?<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-palette-color-20-color has-text-color has-link-color has-aip-font-size wp-elements-7a546f6e64cdec812481b2d79c048563\" style=\"font-style:normal;font-weight:1000;line-height:1\">\u00bfqu\u00e9 hacer?<\/h2>\n\n\n\n<h2 class=\"wp-block-heading has-palette-color-20-color has-text-color has-link-color has-aip-font-size wp-elements-7a546f6e64cdec812481b2d79c048563\" style=\"font-style:normal;font-weight:1000;line-height:1\">\u00bfqu\u00e9 hacer?<\/h2>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-5-background-color has-background is-layout-constrained wp-container-core-group-is-layout-5f93b276 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<p class=\"wp-block-paragraph\" style=\"font-size:clamp(2.2rem, 2.2rem + ((1vw - 0.2rem) * 2.25), 4rem);line-height:1\">Asumimos el desaf\u00edo de construir un solo pu\u00f1o que se levante hermanado para avanzar en la construcci\u00f3n de nuestro propio destino. Las luchas de nuestros pueblos nos muestran el camino.  <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-12-background-color has-background is-layout-constrained wp-container-core-group-is-layout-5f93b276 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<p class=\"wp-block-paragraph\" style=\"font-size:clamp(2.2rem, 2.2rem + ((1vw - 0.2rem) * 2.25), 4rem);line-height:1\">La unidad es nuestro horizonte para avanzar en una gran voluntad popular que construya un mundo justo, igualitario y digno de ser vivido por todas y todos en armon\u00eda con nuestra Madre Tierra. El momento es ahora.  <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-5-background-color has-background is-layout-constrained wp-container-core-group-is-layout-5f93b276 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<div class=\"wp-block-group is-content-justification-right is-layout-constrained wp-container-core-group-is-layout-cc43fbaa wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group pos-relative is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">Nos proponemos fortalecer nuestras conexiones a trav\u00e9s de pr\u00e1cticas concretas y acciones comunes. No pretendemos construir ning\u00fan tipo de organizaci\u00f3n internacional burocr\u00e1tica o vertical. Queremos fortalecer articulaciones internacionales a partir de nuestras experiencias nacionales y de cada organizaci\u00f3n, partido, sindicato, movimiento popular.   <\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:600;line-height:1\">Nuestro objetivo es construir una red que nos ayude a conocer las luchas de cada uno, nos ayude a colaborar de manera concreta y nos ayude a ampliar nuestro trabajo mediante acciones comunes. Necesitamos construir nuestra unidad basada en nuestras ideas ampliamente comunes de justicia e igualdad, en la base de nuestro respeto mutuo por nuestro trabajo y en las acciones comunes que llevaremos a cabo para fortalecer nuestra voluntad y nuestro poder.  <\/p>\n\n\n\n<div id=\"political-platform-float-11\" class=\"wp-block-group float-border-box is-layout-constrained wp-container-core-group-is-layout-3ec51e27 wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading has-palette-color-8-color has-text-color has-link-color has-aip-font-size wp-elements-4dfd21ebd31f1785bb0a0b6668b0ce6e\" style=\"font-style:normal;font-weight:1000;line-height:1\">NUESTRA<br>AGENDA<br>EN COMU\u0301N<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-12-background-color has-background is-layout-constrained wp-container-core-group-is-layout-5f93b276 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<h2 class=\"wp-block-heading float-border-text right has-palette-color-8-color has-text-color has-link-color has-aip-font-size wp-elements-31d86d8a77c92ecf5575ec55e15efc97\" id=\"political-platform-float-12\" style=\"font-style:normal;font-weight:1000;line-height:1\">NUESTRA<br>AGENDA<br>EN COMU\u0301N<\/h2>\n\n\n\n<div class=\"wp-block-group is-content-justification-left is-layout-constrained wp-container-core-group-is-layout-c69cce60 wp-block-group-is-layout-constrained\">\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">El capitalismo no morir\u00e1 de muerte natural, aunque cada d\u00eda aumentan las contradicciones entre la concentraci\u00f3n de riquezas y los pueblos. No se convertir\u00e1 en v\u00edctima de sus propias contradicciones. Las intensas tensiones de nuestro tiempo pueden llevar tanto al neofascismo como a la superaci\u00f3n del capitalismo. Avanzar hacia este \u00faltimo requiere una fuerte organizaci\u00f3n de nuestros pueblos, con unidad organizativa, fuerza de masa y claridad ideol\u00f3gica sobre nuestra situaci\u00f3n actual y nuestro futuro por venir.    <\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\" style=\"font-style:normal;font-weight:600;line-height:1\">Para ese fin, es necesario que en cada uno de nuestros pa\u00edses realicemos nuestras respectivas evaluaciones estrat\u00e9gicas para construir poderosas fuerzas populares, democr\u00e1ticas y revolucionarias y promover una transformaci\u00f3n social radical para enfrentar esta crisis. Tenemos que construir nuestra fuerza para superar el presente t\u00f3xico y pasar a la emancipaci\u00f3n humana.  <\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-5-background-color has-background is-layout-constrained wp-container-core-group-is-layout-5f93b276 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<div class=\"wp-block-group is-content-justification-center is-layout-constrained wp-container-core-group-is-layout-cf04d86b wp-block-group-is-layout-constrained\">\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">La plataforma unitaria, internacional, que aqu\u00ed presentamos debe ser solo un texto para debate para que nuestra militancia profundice sus planteamientos sobre la necesidad de los cambios estructurales y a nivel mundial. Los movimientos dentro de cada pa\u00eds siempre se robustecen cuando tienen fuertes lazos con movimientos en otros lugares cruzando las fronteras nacionales.  <\/p>\n\n\n\n<p class=\"has-p-huge-font-size wp-block-paragraph\" style=\"line-height:1.25\">La creaci\u00f3n de redes a escala internacional nos permite ampliar nuestro trabajo y proporcionar una solidaridad tangible a cada uno de nuestros esfuerzos. Nuestro proceso de Asamblea busca construir una red mundial para fortalecer nuestras batallas a escala nacional y mundial. Nuestra red nos ayudar\u00e1 a compartir informaci\u00f3n y an\u00e1lisis. Proporcionar\u00e1 una plataforma para acciones unitarias a escala mundial para amplificar nuestras posiciones y nuestro poder. Debemos practicar el internacionalismo popular, a trav\u00e9s de formas pr\u00e1cticas, no s\u00f3lo de ideas y slogans.    .  <\/p>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading float-border-text has-palette-color-12-color has-text-color has-link-color has-aip-font-size wp-elements-cf3077cc83a9474148aa1b3f8824b09d\" id=\"political-platform-float-13\" style=\"font-style:normal;font-weight:1000;line-height:1\">\u00bfqu\u00e9 hacer?<\/h2>\n\n\n\n<h2 class=\"wp-block-heading float-border-text right has-palette-color-12-color has-text-color has-link-color has-aip-font-size wp-elements-5f6b0efc78e63cd8d258ae18c6f22c5c\" id=\"political-platform-float-14\" style=\"font-style:normal;font-weight:1000;line-height:1\">\u00bfqu\u00e9 hacer?<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-12-background-color has-background is-layout-constrained wp-container-core-group-is-layout-5f93b276 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<p class=\"wp-block-paragraph\" style=\"font-size:clamp(2.2rem, 2.2rem + ((1vw - 0.2rem) * 2.25), 4rem);line-height:1\">Sin movilizaci\u00f3n popular no podremos acumular fuerzas contra el capitalismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:clamp(2.2rem, 2.2rem + ((1vw - 0.2rem) * 2.25), 4rem);line-height:1\">Sin formaci\u00f3n pol\u00edtica no podremos participar en la batalla de ideas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:clamp(2.2rem, 2.2rem + ((1vw - 0.2rem) * 2.25), 4rem);font-style:normal;font-weight:700;line-height:1\">\u00a1Sin lucha pol\u00edtica, las ideas no avanzan! <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-palette-color-5-background-color has-background is-layout-constrained wp-container-core-group-is-layout-5f93b276 wp-block-group-is-layout-constrained\" style=\"margin-top:0;margin-bottom:0;padding-top:var(--wp--preset--spacing--60);padding-bottom:var(--wp--preset--spacing--60)\">\n<div class=\"wp-block-group is-content-justification-right is-layout-constrained wp-container-core-group-is-layout-cc43fbaa wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group pos-relative is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\" style=\"font-size:clamp(2.2rem, 2.2rem + ((1vw - 0.2rem) * 2.25), 4rem);font-style:normal;font-weight:700;line-height:1\">Nuestra verdadera fuerza est\u00e1 en la capacidad de organizar a los pueblos para que luchen, de forma unitaria y masiva, por un mundo diferente.<\/p>\n\n\n\n<div id=\"political-platform-float-15\" class=\"wp-block-group has-palette-color-12-background-color has-background is-layout-constrained wp-block-group-is-layout-constrained\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>PLATAFORMAPOLITICA UN MUNDO EN CRISIS Estamos atravesando un per\u00edodo largo de una crisis estructural y profunda del capitalismo. Se trata de una crisis del modo de producci\u00f3n capitalista que ha devenido en una profunda crisis social, por la profundizaci\u00f3n de las desigualdades, aumento de la pobreza, del hambre, de la precarizaci\u00f3n y despojo de derechos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-989","page","type-page","status-publish","hentry"],"blocksy_meta":{"has_hero_section":"disabled","vertical_spacing_source":"custom","content_area_spacing":"none","styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"acf":[],"_links":{"self":[{"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/pages\/989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/comments?post=989"}],"version-history":[{"count":2,"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/pages\/989\/revisions"}],"predecessor-version":[{"id":8154,"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/pages\/989\/revisions\/8154"}],"wp:attachment":[{"href":"https:\/\/ipa-aip.org\/es\/wp-json\/wp\/v2\/media?parent=989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}